
{"id":298370,"date":"2016-02-22T05:00:00","date_gmt":"2016-02-22T05:00:00","guid":{"rendered":"https:\/\/integralads.com\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/"},"modified":"2016-02-22T05:00:00","modified_gmt":"2016-02-22T05:00:00","slug":"ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability","status":"publish","type":"portfolio","link":"https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/","title":{"rendered":"Integral Ad Science Report: Leichte Verbesserungen bei der Viewability"},"content":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><strong>Berlin, 22. Februar 2016<\/strong> &#8211; Integral Ad Science, f\u00fchrender globaler Anbieter f\u00fcr die \u00dcberpr\u00fcfung von Werbeplatzierungen und Markensicherheit, hat seinen Media Quality Report f\u00fcr das vierte Quartal 2015 vorgelegt. Aus dem Report geht hervor, dass sich die Mediaqualit\u00e4t des deutschen Werbemarktes insgesamt etwas verbessert hat. Allerdings gibt es weiterhin ein ernstes Problem mit betr\u00fcgerischen Werbeanzeigen, sogenanntem Ad Fraud. Der Anteil an Ad Fraud lag im vergangenen Quartal bei nicht unerheblichen 7,9 Prozent. Der Report basiert auf den gesammelten Daten aus Milliarden von Impressions, die das Unternehmen jedes Quartal analysiert, um einen \u00dcberblick \u00fcber die weltweite Mediaqualit\u00e4t zu erhalten. Hierbei wird insbesondere die Entwicklung von Ad Fraud, Viewability und Brand Risk im Hinblick auf Video- und Display-Advertising untersucht.<\/p>\n<p>Betrachtet man die Viewability, so hat sich die Sichtbarkeit von Werbeanzeigen im vierten Quartal mit 53,4 Prozent verglichen mit 51,1 Prozent in Q3 leicht verbessert. Vor dem Hintergrund der in der Branche vieldiskutierten Problematik nicht-sichtbarer Anzeigen ist die Verbesserung der Viewability um 2,3 Prozent besonders hervorzu-heben. Der True Advertising Quality Score (TRAQ-Score), Integrals Indikator f\u00fcr die Medienqualit\u00e4t \u00fcber alle Kan\u00e4le, ist mit 632 Punkten gegen\u00fcber dem dritten Quartal gleich geblieben.<\/p>\n<p>\u201eWir freuen uns dar\u00fcber, dass sich die Viewability im letzten Quartal leicht verbessert hat. Gleichzeitig m\u00fcssen wir nochmals betonen, dass es in Deutschland nach wie vor ein massives Problem mit Ad Fraud gibt. Mit unserer Software-L\u00f6sung k\u00f6nnen Publisher und Agenturen gezielt gegen Ad Fraud vorgehen und betr\u00fcgerische Anzeigen erkennen sowie eliminieren\u201c, sagt Olaf Mahr, Managing Director DACH bei Integral Ad Science. \u201eDar\u00fcber hinaus bieten wir die umfassendste Viewability-Messmethodik an, die aktuell am Markt erh\u00e4ltlich ist. Trotz vieler kreativer Ans\u00e4tze einzelner Anbieter erreichen wir \u00fcber 95 Prozent Messbarkeit und k\u00f6nnen auch die Qualit\u00e4t von Ads aus den Bereichen Video und Mobile gezielt messen.\u201c<\/p>\n<p>Schaut man sich die Ergebnisse f\u00fcr Deutschland im europ\u00e4ischen Vergleich an, so weichen die Zahlen zu Ad Fraud und Viewability aktuell kaum von den Werten aus Frankreich und UK ab. Der Anteil von Ad Fraud ist mit 7,9 Prozent nur geringf\u00fcgig h\u00f6her als in UK (7,8 Prozent) und Frankreich (6,0 Prozent). Auch die Viewability schneidet im deutschen Markt mit 53,4 Prozent \u00e4hnlich ab wie in UK (50,1 Prozent) und Frankreich (53,5 Prozent).<\/span><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integral Ad Science hat seinen Media Quality Report f\u00fcr das vierte Quartal 2015 vorgelegt. Aus dem Report geht hervor, dass sich die Mediaqualit\u00e4t des deutschen Werbemarktes insgesamt etwas verbessert hat.<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","portfolio-types":[77],"class_list":["post-298370","portfolio","type-portfolio","status-publish","hentry","portfolio-types-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Integral Ad Science Report: Leichte Verbesserungen bei der Viewability - Integral Ad Science<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Integral Ad Science Report: Leichte Verbesserungen bei der Viewability\" \/>\n<meta property=\"og:description\" content=\"Integral Ad Science hat seinen Media Quality Report f\u00fcr das vierte Quartal 2015 vorgelegt. Aus dem Report geht hervor, dass sich die Mediaqualit\u00e4t des deutschen Werbemarktes insgesamt etwas verbessert hat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/\" \/>\n<meta property=\"og:site_name\" content=\"Integral Ad Science\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@integralads\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/integralads.com\\\/de\\\/news\\\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\\\/\",\"url\":\"https:\\\/\\\/integralads.com\\\/de\\\/news\\\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\\\/\",\"name\":\"Integral Ad Science Report: Leichte Verbesserungen bei der Viewability - Integral Ad Science\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#website\"},\"datePublished\":\"2016-02-22T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/de\\\/news\\\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/integralads.com\\\/de\\\/news\\\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/integralads.com\\\/de\\\/news\\\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/integralads.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Integral Ad Science Report: Leichte Verbesserungen bei der Viewability\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#website\",\"url\":\"https:\\\/\\\/integralads.com\\\/\",\"name\":\"Integral Ad Science\",\"description\":\"The Hidden Cost of MFA Webinar\",\"publisher\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/integralads.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#organization\",\"name\":\"Integral Ad Science\",\"url\":\"https:\\\/\\\/integralads.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IAS_Square-Logo-600x600-1.png\",\"contentUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IAS_Square-Logo-600x600-1.png\",\"width\":600,\"height\":600,\"caption\":\"Integral Ad Science\"},\"image\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/integralads\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Integral Ad Science Report: Leichte Verbesserungen bei der Viewability - Integral Ad Science","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/","og_locale":"de_DE","og_type":"article","og_title":"Integral Ad Science Report: Leichte Verbesserungen bei der Viewability","og_description":"Integral Ad Science hat seinen Media Quality Report f\u00fcr das vierte Quartal 2015 vorgelegt. Aus dem Report geht hervor, dass sich die Mediaqualit\u00e4t des deutschen Werbemarktes insgesamt etwas verbessert hat.","og_url":"https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/","og_site_name":"Integral Ad Science","twitter_card":"summary_large_image","twitter_site":"@integralads","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/","url":"https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/","name":"Integral Ad Science Report: Leichte Verbesserungen bei der Viewability - Integral Ad Science","isPartOf":{"@id":"https:\/\/integralads.com\/#website"},"datePublished":"2016-02-22T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/integralads.com\/de\/news\/ias-report-q4-2015-leichte-verbesserungen-bei-der-viewability\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/integralads.com\/de\/"},{"@type":"ListItem","position":2,"name":"Integral Ad Science Report: Leichte Verbesserungen bei der Viewability"}]},{"@type":"WebSite","@id":"https:\/\/integralads.com\/#website","url":"https:\/\/integralads.com\/","name":"Integral Ad Science","description":"The Hidden Cost of MFA Webinar","publisher":{"@id":"https:\/\/integralads.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/integralads.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/integralads.com\/#organization","name":"Integral Ad Science","url":"https:\/\/integralads.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/integralads.com\/#\/schema\/logo\/image\/","url":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/10\/IAS_Square-Logo-600x600-1.png","contentUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/10\/IAS_Square-Logo-600x600-1.png","width":600,"height":600,"caption":"Integral Ad Science"},"image":{"@id":"https:\/\/integralads.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/integralads"]}]}},"_links":{"self":[{"href":"https:\/\/integralads.com\/de\/wp-json\/wp\/v2\/portfolio\/298370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integralads.com\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/integralads.com\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/integralads.com\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/integralads.com\/de\/wp-json\/wp\/v2\/portfolio\/298370\/revisions"}],"wp:attachment":[{"href":"https:\/\/integralads.com\/de\/wp-json\/wp\/v2\/media?parent=298370"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/integralads.com\/de\/wp-json\/wp\/v2\/portfolio-types?post=298370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}