{"id":318052,"date":"2023-03-20T09:43:00","date_gmt":"2023-03-20T09:43:00","guid":{"rendered":"https:\/\/integralads.com\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/"},"modified":"2023-03-20T09:43:00","modified_gmt":"2023-03-20T09:43:00","slug":"la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix","status":"publish","type":"portfolio","link":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/","title":{"rendered":"LA SOLUZIONE DI VERIFICA DELLA MEDIA QUALITY DI INTEGRAL AD SCIENCE E\u2019 LIVE CON NETFLIX"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>IAS collabora con Netflix per fornire agli inserzionisti metriche di verifica fondamentali per il nuovo piano supportato dalla pubblicit\u00e0<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milano, 20 marzo 2023 <\/strong>\u2013&nbsp;Integral Ad Science (Nasdaq: IAS), leader globale nella qualit\u00e0 dei media digitali, ha lanciato oggi la verifica della Viewability e del Traffico Non Valido per il piano pubblicitario di Netflix (Nasdaq:NFLX), dopo l&#8217;<a href=\"https:\/\/about.netflix.com\/en\/news\/announcing-basic-with-ads-us\">annuncio<\/a> della partnership nel 2022. Queste soluzioni assicurano che le campagne pubblicitarie in corso su Netflix vengano erogate senza frodi e siano viste da spettatori reali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il programma di verifica degli annunci pubblicitari, indipendente e di terza parte di IAS per Netflix, va ben oltre le tradizionali valutazioni televisive, consentendo a brand e agenzie di ottenere informazioni sulla reach e sull\u2019engagement delle campagne. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I principali vantaggi della soluzione includono:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Un reporting <strong>indipendente <\/strong>e di terza parte nella piattaforma IAS Signal;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; <strong>Massimizzazione delle informazioni<\/strong> attraverso l&#8217;identificazione dei trend e l&#8217;ottimizzazione delle campagne in base all&#8217;engagement;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; <strong>Misurazione uniforme<\/strong> tra i media acquistati per comprendere le performance nell&#8217;intero ecosistema digitale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;I marketer dispongono ora di nuovi potenti strumenti per assicurare che gli annunci pubblicitari su Netflix coinvolgano gli spettatori&#8221;, ha dichiarato Lisa Utzschneider, CEO di IAS. &#8220;Con l&#8217;avvio di questa partnership, gli inserzionisti possono investire con fiducia nell&#8217;espansione delle loro strategie media all&#8217;inventory premium di Netflix&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il programma di verifica di IAS per Netflix \u00e8 ora attivo in tutti i 12 Paesi in cui Netflix supporta gli annunci pubblicitari e su tutte le piattaforme: connected tv, computer e mobile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La soluzione IAS assicura che le campagne pubblicitarie in corso su Netflix vengano erogate senza frodi e siano viste da spettatori reali.<\/p>\n","protected":false},"author":1,"featured_media":318053,"menu_order":0,"template":"","portfolio-types":[571,573],"class_list":["post-318052","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-notizia","portfolio-types-rassegna-stampa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LA SOLUZIONE DI VERIFICA DELLA MEDIA QUALITY DI INTEGRAL AD SCIENCE E\u2019 LIVE CON NETFLIX - Integral Ad Science<\/title>\n<meta name=\"description\" content=\"La soluzione IAS assicura che le campagne pubblicitarie in corso su Netflix vengano erogate senza frodi e siano viste da spettatori reali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA SOLUZIONE DI VERIFICA DELLA MEDIA QUALITY DI INTEGRAL AD SCIENCE E\u2019 LIVE CON NETFLIX\" \/>\n<meta property=\"og:description\" content=\"La soluzione IAS assicura che le campagne pubblicitarie in corso su Netflix vengano erogate senza frodi e siano viste da spettatori reali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/\" \/>\n<meta property=\"og:site_name\" content=\"Integral Ad Science\" \/>\n<meta property=\"og:image\" content=\"https:\/\/integralads.com\/wp-content\/uploads\/2023\/09\/IAS-Netflix-Measurement-2023_600x300_Email-Header-IT.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@integralads\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\\\/\",\"url\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\\\/\",\"name\":\"LA SOLUZIONE DI VERIFICA DELLA MEDIA QUALITY DI INTEGRAL AD SCIENCE E\u2019 LIVE CON NETFLIX - Integral Ad Science\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IAS-Netflix-Measurement-2023_600x300_Email-Header-IT.png\",\"datePublished\":\"2023-03-20T09:43:00+00:00\",\"description\":\"La soluzione IAS assicura che le campagne pubblicitarie in corso su Netflix vengano erogate senza frodi e siano viste da spettatori reali.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\\\/#primaryimage\",\"url\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IAS-Netflix-Measurement-2023_600x300_Email-Header-IT.png\",\"contentUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IAS-Netflix-Measurement-2023_600x300_Email-Header-IT.png\",\"width\":1250,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/integralads.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA SOLUZIONE DI VERIFICA DELLA MEDIA QUALITY DI INTEGRAL AD SCIENCE E\u2019 LIVE CON NETFLIX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#website\",\"url\":\"https:\\\/\\\/integralads.com\\\/\",\"name\":\"Integral Ad Science\",\"description\":\"The Hidden Cost of MFA Webinar\",\"publisher\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/integralads.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#organization\",\"name\":\"Integral Ad Science\",\"url\":\"https:\\\/\\\/integralads.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IAS_Square-Logo-600x600-1.png\",\"contentUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IAS_Square-Logo-600x600-1.png\",\"width\":600,\"height\":600,\"caption\":\"Integral Ad Science\"},\"image\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/integralads\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LA SOLUZIONE DI VERIFICA DELLA MEDIA QUALITY DI INTEGRAL AD SCIENCE E\u2019 LIVE CON NETFLIX - Integral Ad Science","description":"La soluzione IAS assicura che le campagne pubblicitarie in corso su Netflix vengano erogate senza frodi e siano viste da spettatori reali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/","og_locale":"it_IT","og_type":"article","og_title":"LA SOLUZIONE DI VERIFICA DELLA MEDIA QUALITY DI INTEGRAL AD SCIENCE E\u2019 LIVE CON NETFLIX","og_description":"La soluzione IAS assicura che le campagne pubblicitarie in corso su Netflix vengano erogate senza frodi e siano viste da spettatori reali.","og_url":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/","og_site_name":"Integral Ad Science","og_image":[{"width":1250,"height":625,"url":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/09\/IAS-Netflix-Measurement-2023_600x300_Email-Header-IT.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@integralads","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/","url":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/","name":"LA SOLUZIONE DI VERIFICA DELLA MEDIA QUALITY DI INTEGRAL AD SCIENCE E\u2019 LIVE CON NETFLIX - Integral Ad Science","isPartOf":{"@id":"https:\/\/integralads.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/#primaryimage"},"image":{"@id":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/#primaryimage"},"thumbnailUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/09\/IAS-Netflix-Measurement-2023_600x300_Email-Header-IT.png","datePublished":"2023-03-20T09:43:00+00:00","description":"La soluzione IAS assicura che le campagne pubblicitarie in corso su Netflix vengano erogate senza frodi e siano viste da spettatori reali.","breadcrumb":{"@id":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/#primaryimage","url":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/09\/IAS-Netflix-Measurement-2023_600x300_Email-Header-IT.png","contentUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/09\/IAS-Netflix-Measurement-2023_600x300_Email-Header-IT.png","width":1250,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/integralads.com\/it\/news\/la-soluzione-di-verifica-della-media-quality-di-integral-ad-science-e-live-con-netflix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/integralads.com\/it\/"},{"@type":"ListItem","position":2,"name":"LA SOLUZIONE DI VERIFICA DELLA MEDIA QUALITY DI INTEGRAL AD SCIENCE E\u2019 LIVE CON NETFLIX"}]},{"@type":"WebSite","@id":"https:\/\/integralads.com\/#website","url":"https:\/\/integralads.com\/","name":"Integral Ad Science","description":"The Hidden Cost of MFA Webinar","publisher":{"@id":"https:\/\/integralads.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/integralads.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/integralads.com\/#organization","name":"Integral Ad Science","url":"https:\/\/integralads.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/integralads.com\/#\/schema\/logo\/image\/","url":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/10\/IAS_Square-Logo-600x600-1.png","contentUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/10\/IAS_Square-Logo-600x600-1.png","width":600,"height":600,"caption":"Integral Ad Science"},"image":{"@id":"https:\/\/integralads.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/integralads"]}]}},"_links":{"self":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio\/318052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio\/318052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/media\/318053"}],"wp:attachment":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/media?parent=318052"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio-types?post=318052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}