
{"id":343670,"date":"2025-09-16T22:40:00","date_gmt":"2025-09-16T22:40:00","guid":{"rendered":"https:\/\/integralads.com\/?post_type=portfolio&#038;p=343670"},"modified":"2025-09-22T16:43:26","modified_gmt":"2025-09-22T16:43:26","slug":"ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale","status":"publish","type":"portfolio","link":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/","title":{"rendered":"IAS e Good-Loop annunciano un\u2019offerta avanzata di misurazione delle emissioniper consentire a tutti gli inserzionistidi tracciare e ridurre ulteriormente l\u2019impatto ambientale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>La nuova collaborazione offre una misurazione avanzata delle emissioni<br>senza costi aggiuntivi per tutti i clienti IAS a livello globale<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milano, 16 settembre 2025<\/strong> \u2013 Integral Ad Science (Nasdaq: IAS), piattaforma globale leader nella misurazione e ottimizzazione dei media, ha annunciato oggi un passo significativo verso la decarbonizzazione universale dei <em>digital media<\/em>, in partnership con la <em>responsible media platform<\/em> Good-Loop. Dopo il lancio del Global Media Sustainability Framework 1.2 (GMSF) a Cannes, IAS consente ora agli inserzionisti di misurare in modo diretto e fluido le emissioni di ogni <em>ad impression<\/em> erogata sull\u2019open internet, senza alcun costo aggiuntivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con l\u2019entrata in vigore, in tutto il mondo, di nuove normative sulle emissioni di carbonio e con i brand che lavorano a nuovi obiettivi di sostenibilit\u00e0, la misurazione delle emissioni \u00e8 rapidamente diventata un pilastro essenziale tra le <em>media quality metrics<\/em>, accanto agli standard consolidati di IAS come <em>viewability, <\/em>prevenzione delle frodi<em>, brand safety &amp; suitability<\/em> e <em>geographic accuracy<\/em>. Integrando in modo fluido le metriche della sostenibilit\u00e0 nella propria suite di soluzioni di media quality, IAS consente agli inserzionisti non solo di garantire che le proprie campagne vengano viste da persone reali in contesti adeguati, ma anche di misurare e ridurre l\u2019impatto ambientale di ogni campagna digitale sull\u2019open web, aiutando i brand a ottenere risultati con maggiore trasparenza e responsabilit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Good-Loop, Certified B Corporation con la mission di offrire pubblicit\u00e0 positiva e climate-friendly, eroga la misurazione delle emissioni all\u2019interno della piattaforma IAS gi\u00e0 da tre anni. In questo arco temporale, IAS e Good-Loop hanno collaborato con alcuni inserzionisti pionieri per definire benchmark fondamentali, sostenendo al contempo l\u2019Advertising Association e Ad Net Zero nello sviluppo di uno standard universale di settore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>In parallelo all\u2019evoluzione delle metodologie e delle tecnologie in questo ambito, \u00e8 cresciuta anche la nostra ambizione<\/em>\u201d racconta Amy Williams, Founder &amp; CEO di Good-Loop. \u201c<em>Ora conosciamo senza alcun dubbio l\u2019impatto ambientale che il <\/em>media buying<em> comporta, ed \u00e8 giunto il momento di portare queste informazioni al cuore del mercato, per cambiare in meglio la nostra <\/em>industry<em>. Ecco perch\u00e9 sono entusiasta di annunciare oggi che i clienti IAS, a livello globale, potranno comprendere &#8211; e quindi ridurre \u2013 la <\/em>carbon footprint<em> dei loro investimenti media nella grande maggioranza delle loro campagne digital<\/em>.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>La sostenibilit\u00e0 nella pubblicit\u00e0 richiede pi\u00f9 delle promesse: serve responsabilit\u00e0. Crediamo che questo livello di trasparenza sia essenziale per guidare un cambiamento concreto nel settore e lo stiamo garantendo ai pi\u00f9 alti standard grazie alla partnership con i principali provider globali di misurazione del carbonio<\/em>\u201d aggiunge Lisa Utzschneider, CEO di Integral Ad Science. \u201c<em>Siamo orgogliosi di questo ulteriore passo con Good-Loop affinch\u00e9 ogni impression che misuriamo sull\u2019open internet sia accompagnata da dati concreti sul suo impatto ambientale, come parte integrante delle media quality metrics, e contribuire a rendere questa pratica uno standard per tutti gli inserzionisti con cui collaboriamo, ovunque nel mondo<\/em>.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Esiste un\u2019esigenza urgente di avere un approccio coerente al calcolo delle emissioni e siamo lieti di vedere il crescente supporto del settore e l\u2019adozione del GMSF<\/em>\u201d continua Anthony Falco, Global Media Sustainability Director di Ad Net Zero. \u201c<em>Ci\u00f2 che si riesce a calcolare si riesce a gestire, quindi portare i dati sulle emissioni in primo piano \u00e8 un passo significativo verso un cambiamento di comportamento duraturo.<\/em>\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando si tratta di proteggere il pianeta, i fatti contano pi\u00f9 delle parole, e IAS e Good-Loop sono entrambe organizzazioni che prendono estremamente sul serio la sostenibilit\u00e0 ambientale. IAS ha pubblicato volontariamente i propri dati con <em>The Climate Registry<\/em> e sta ora fissando ufficialmente obiettivi Net Zero verificati da SBTi, unendosi a oltre 10.000 aziende, tra cui Good-Loop, sul percorso pubblicamente verificato verso il Net Zero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nuova collaborazione offre una misurazione avanzata delle emissionisenza costi aggiuntivi per tutti i clienti IAS a livello globale Milano, 16 settembre 2025 \u2013 Integral Ad Science (Nasdaq: IAS), piattaforma globale leader nella misurazione e ottimizzazione dei media, ha annunciato&#8230;<\/p>\n","protected":false},"author":1,"featured_media":343631,"menu_order":0,"template":"","portfolio-types":[572],"class_list":["post-343670","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-copertura-mediatica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>IAS e Good-Loop annunciano un\u2019offerta avanzata di misurazione delle emissioniper consentire a tutti gli inserzionistidi tracciare e ridurre ulteriormente l\u2019impatto ambientale - Integral Ad Science<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IAS e Good-Loop annunciano un\u2019offerta avanzata di misurazione delle emissioniper consentire a tutti gli inserzionistidi tracciare e ridurre ulteriormente l\u2019impatto ambientale\" \/>\n<meta property=\"og:description\" content=\"La nuova collaborazione offre una misurazione avanzata delle emissionisenza costi aggiuntivi per tutti i clienti IAS a livello globale Milano, 16 settembre 2025 \u2013 Integral Ad Science (Nasdaq: IAS), piattaforma globale leader nella misurazione e ottimizzazione dei media, ha annunciato...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/\" \/>\n<meta property=\"og:site_name\" content=\"Integral Ad Science\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T16:43:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/integralads.com\/wp-content\/uploads\/2025\/09\/Good-Loop-Lockup-2-image-bg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@integralads\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\\\/\",\"url\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\\\/\",\"name\":\"IAS e Good-Loop annunciano un\u2019offerta avanzata di misurazione delle emissioniper consentire a tutti gli inserzionistidi tracciare e ridurre ulteriormente l\u2019impatto ambientale - Integral Ad Science\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Good-Loop-Lockup-2-image-bg.png\",\"datePublished\":\"2025-09-16T22:40:00+00:00\",\"dateModified\":\"2025-09-22T16:43:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Good-Loop-Lockup-2-image-bg.png\",\"contentUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Good-Loop-Lockup-2-image-bg.png\",\"width\":1200,\"height\":1200,\"caption\":\"Good-Loop - Lockup 2 - image bg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/integralads.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IAS e Good-Loop annunciano un\u2019offerta avanzata di misurazione delle emissioniper consentire a tutti gli inserzionistidi tracciare e ridurre ulteriormente l\u2019impatto ambientale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#website\",\"url\":\"https:\\\/\\\/integralads.com\\\/\",\"name\":\"Integral Ad Science\",\"description\":\"The Hidden Cost of MFA Webinar\",\"publisher\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/integralads.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#organization\",\"name\":\"Integral Ad Science\",\"url\":\"https:\\\/\\\/integralads.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IAS_Square-Logo-600x600-1.png\",\"contentUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IAS_Square-Logo-600x600-1.png\",\"width\":600,\"height\":600,\"caption\":\"Integral Ad Science\"},\"image\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/integralads\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"IAS e Good-Loop annunciano un\u2019offerta avanzata di misurazione delle emissioniper consentire a tutti gli inserzionistidi tracciare e ridurre ulteriormente l\u2019impatto ambientale - Integral Ad Science","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/","og_locale":"it_IT","og_type":"article","og_title":"IAS e Good-Loop annunciano un\u2019offerta avanzata di misurazione delle emissioniper consentire a tutti gli inserzionistidi tracciare e ridurre ulteriormente l\u2019impatto ambientale","og_description":"La nuova collaborazione offre una misurazione avanzata delle emissionisenza costi aggiuntivi per tutti i clienti IAS a livello globale Milano, 16 settembre 2025 \u2013 Integral Ad Science (Nasdaq: IAS), piattaforma globale leader nella misurazione e ottimizzazione dei media, ha annunciato...","og_url":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/","og_site_name":"Integral Ad Science","article_modified_time":"2025-09-22T16:43:26+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/integralads.com\/wp-content\/uploads\/2025\/09\/Good-Loop-Lockup-2-image-bg.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@integralads","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/","url":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/","name":"IAS e Good-Loop annunciano un\u2019offerta avanzata di misurazione delle emissioniper consentire a tutti gli inserzionistidi tracciare e ridurre ulteriormente l\u2019impatto ambientale - Integral Ad Science","isPartOf":{"@id":"https:\/\/integralads.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/#primaryimage"},"image":{"@id":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/#primaryimage"},"thumbnailUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2025\/09\/Good-Loop-Lockup-2-image-bg.png","datePublished":"2025-09-16T22:40:00+00:00","dateModified":"2025-09-22T16:43:26+00:00","breadcrumb":{"@id":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/#primaryimage","url":"https:\/\/integralads.com\/wp-content\/uploads\/2025\/09\/Good-Loop-Lockup-2-image-bg.png","contentUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2025\/09\/Good-Loop-Lockup-2-image-bg.png","width":1200,"height":1200,"caption":"Good-Loop - Lockup 2 - image bg"},{"@type":"BreadcrumbList","@id":"https:\/\/integralads.com\/it\/news\/ias-e-good-loop-annunciano-unofferta-avanzata-di-misurazione-delle-emissioniper-consentire-a-tutti-gli-inserzionistidi-tracciare-e-ridurre-ulteriormente-limpatto-ambientale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/integralads.com\/it\/"},{"@type":"ListItem","position":2,"name":"IAS e Good-Loop annunciano un\u2019offerta avanzata di misurazione delle emissioniper consentire a tutti gli inserzionistidi tracciare e ridurre ulteriormente l\u2019impatto ambientale"}]},{"@type":"WebSite","@id":"https:\/\/integralads.com\/#website","url":"https:\/\/integralads.com\/","name":"Integral Ad Science","description":"The Hidden Cost of MFA Webinar","publisher":{"@id":"https:\/\/integralads.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/integralads.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/integralads.com\/#organization","name":"Integral Ad Science","url":"https:\/\/integralads.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/integralads.com\/#\/schema\/logo\/image\/","url":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/10\/IAS_Square-Logo-600x600-1.png","contentUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/10\/IAS_Square-Logo-600x600-1.png","width":600,"height":600,"caption":"Integral Ad Science"},"image":{"@id":"https:\/\/integralads.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/integralads"]}]}},"_links":{"self":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio\/343670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio\/343670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/media\/343631"}],"wp:attachment":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/media?parent=343670"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio-types?post=343670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}