
{"id":344182,"date":"2025-10-16T18:34:00","date_gmt":"2025-10-16T18:34:00","guid":{"rendered":"https:\/\/integralads.com\/?post_type=portfolio&#038;p=344182"},"modified":"2025-10-30T16:43:32","modified_gmt":"2025-10-30T16:43:32","slug":"ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta","status":"publish","type":"portfolio","link":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/","title":{"rendered":"IAS presenta al mercato la prima misurazione indipendente basata su AI per rilevare Brand Safety &amp; Suitability su Threads di Meta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>La partnership ampliata con Meta rafforza la protezione dei brand<\/em> <em>e massimizza il ROI per gli inserzionisti globali<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milano, 16 ottobre 2025 <\/strong>\u2013 Integral Ad Science (Nasdaq: IAS), piattaforma globale leader nella misurazione e ottimizzazione dei media, ha annunciato oggi l&#8217;estensione di Total Media Quality (TMQ) su Meta, introducendo per la prima volta una misurazione indipendente e di terze parti riferita alla rilevazione della Brand Safety &amp; Suitability su Threads. Basata sull\u2019innovativa tecnologia multimediale di IAS guidata dall\u2019intelligenza artificiale, che utilizza segnali provenienti da video, immagini, audio e testo per valutare i contenuti su larga scala, Total Media Quality su\u00a0 Meta Threads aiuta gli inserzionisti a proteggere la reputazione del brand e a gestire le campagne in tempo reale in modo sicuro e scalabile. L\u2019integrazione amplia la copertura pre e post-bid di IAS, includendo anche Facebook,\u00a0 Instagram Feed e Reels.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>L\u2019analisi dei contenuti basata su AI di IAS consente agli inserzionisti di migliorare le performance e di ampliare con fiducia i propri investimenti, grazie a una misurazione affidabile, indipendente e fornita da terze parti<\/em>\u201d racconta <strong>Lisa Utzschneider<\/strong>, <strong>CEO di IAS<\/strong>. \u201c<em>Continuiamo a innovare e a rafforzare le nostre collaborazioni con partner globali come Meta, al fine di offrire agli inserzionisti un supporto completo per le campagne servite su&nbsp; tutti i canali e dispositivi<\/em>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Threads \u00e8 una piattaforma in rapida crescita, con oltre 400 milioni di utenti attivi mensili a livello globale (dati di agosto 2025). La misurazione di Brand Safety e Suitability di IAS per Threads offre agli inserzionisti di tutto il mondo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Una verifica indipendente di terze parti<\/strong> garantendo che i contenuti affiancati agli annunci siano sicuri e pertinenti Questo inoltre consente agli inserzionisti di capire le prestazioni dei propri Inventory Filters nel feed di threads, metterli\u00a0 in relazione agli obiettivi delle campagne e\u00a0 ottimizzarli quando necessario;<\/li>\n\n\n\n<li><strong>analisi approfondite a livello di contenuto<\/strong>, con impostazioni personalizzate di suitability all\u2019interno di IAS Signal, la piattaforma di reportistica\u00a0 IAS che offre agli inserzionisti una visione completa ed integrata delle proprie campagne;<\/li>\n\n\n\n<li><strong>una classificazione conforme agli standard di settore<\/strong>, con analisi dettagliate suddivise per categorie chiave e livelli di rischio;<\/li>\n\n\n\n<li><strong>un\u2019analisi dei contenuti basata su AI grazie alla tecnologia multimediale di IAS frame by frame level: <\/strong>solo IAS \u00e8 in grado di analizzare i contenuti fotogramma per fotogramma, combinando segnali visivi, audio e testuali garantendo una classificazione precisa e di altissimo livello;<\/li>\n\n\n\n<li><strong>Una copertura globale <\/strong>in 34 lingue, che mette a disposizione degli inserzionisti una soluzione completa e su scala internazionale per la piattaforma.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nell\u2019ottobre dello scorso anno, <a href=\"https:\/\/integralads.com\/news\/ias-meta-optimization-solution\/\">IAS ha annunciato il lancio delle sue Content Block Lists per Meta<\/a>, diventando il primo provider sul mercato a sviluppare questa soluzione di ottimizzazione dopo essere stato selezionato come fornitore principale. Nell\u2019aprile 2024, IAS ha comunicato l\u2019ampliamento della sua soluzione di <a href=\"about:blank\">Brand Safety and Suitability Measurement, includendo la categoria della misinformation, in linea con gli standard di settore per Facebook<\/a><a href=\"about:blank\">, <\/a><a href=\"about:blank\">&nbsp;Instagram Feed e Reels<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infine, nel febbraio 2024, IAS ha reso noto la disponibilit\u00e0 della sua soluzione <a href=\"https:\/\/integralads.com\/news\/ias-expands-ai-driven-brand-safety-and-suitability-measurement-to-meta\/\">AI-driven Total Media Quality (TMQ) Brand Safety and Suitability Measurement su Facebook e Instagram Feed e Reels<\/a>, in collaborazione con Meta, per offrire agli inserzionisti una copertura avanzata e una misurazione ai massimi livelli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La partnership ampliata con Meta rafforza la protezione dei brand e massimizza il ROI per gli inserzionisti globali Milano, 16 ottobre 2025 \u2013 Integral Ad Science (Nasdaq: IAS), piattaforma globale leader nella misurazione e ottimizzazione dei media, ha annunciato oggi&#8230;<\/p>\n","protected":false},"author":1,"featured_media":344023,"menu_order":0,"template":"","portfolio-types":[572],"class_list":["post-344182","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-copertura-mediatica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>IAS presenta al mercato la prima misurazione indipendente basata su AI per rilevare Brand Safety &amp; Suitability su Threads di Meta - Integral Ad Science<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IAS presenta al mercato la prima misurazione indipendente basata su AI per rilevare Brand Safety &amp; Suitability su Threads di Meta\" \/>\n<meta property=\"og:description\" content=\"La partnership ampliata con Meta rafforza la protezione dei brand e massimizza il ROI per gli inserzionisti globali Milano, 16 ottobre 2025 \u2013 Integral Ad Science (Nasdaq: IAS), piattaforma globale leader nella misurazione e ottimizzazione dei media, ha annunciato oggi...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/\" \/>\n<meta property=\"og:site_name\" content=\"Integral Ad Science\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T16:43:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/integralads.com\/wp-content\/uploads\/2025\/10\/Meta-Lockup-v2b.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@integralads\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\\\/\",\"url\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\\\/\",\"name\":\"IAS presenta al mercato la prima misurazione indipendente basata su AI per rilevare Brand Safety &amp; Suitability su Threads di Meta - Integral Ad Science\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Meta-Lockup-v2b.png\",\"datePublished\":\"2025-10-16T18:34:00+00:00\",\"dateModified\":\"2025-10-30T16:43:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Meta-Lockup-v2b.png\",\"contentUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Meta-Lockup-v2b.png\",\"width\":1200,\"height\":1200,\"caption\":\"Meta - Lockup v2b\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/integralads.com\\\/it\\\/news\\\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/integralads.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IAS presenta al mercato la prima misurazione indipendente basata su AI per rilevare Brand Safety &amp; Suitability su Threads di Meta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#website\",\"url\":\"https:\\\/\\\/integralads.com\\\/\",\"name\":\"Integral Ad Science\",\"description\":\"The Hidden Cost of MFA Webinar\",\"publisher\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/integralads.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#organization\",\"name\":\"Integral Ad Science\",\"url\":\"https:\\\/\\\/integralads.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/integralads.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IAS_Square-Logo-600x600-1.png\",\"contentUrl\":\"https:\\\/\\\/integralads.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IAS_Square-Logo-600x600-1.png\",\"width\":600,\"height\":600,\"caption\":\"Integral Ad Science\"},\"image\":{\"@id\":\"https:\\\/\\\/integralads.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/integralads\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"IAS presenta al mercato la prima misurazione indipendente basata su AI per rilevare Brand Safety &amp; Suitability su Threads di Meta - Integral Ad Science","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/","og_locale":"it_IT","og_type":"article","og_title":"IAS presenta al mercato la prima misurazione indipendente basata su AI per rilevare Brand Safety &amp; Suitability su Threads di Meta","og_description":"La partnership ampliata con Meta rafforza la protezione dei brand e massimizza il ROI per gli inserzionisti globali Milano, 16 ottobre 2025 \u2013 Integral Ad Science (Nasdaq: IAS), piattaforma globale leader nella misurazione e ottimizzazione dei media, ha annunciato oggi...","og_url":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/","og_site_name":"Integral Ad Science","article_modified_time":"2025-10-30T16:43:32+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/integralads.com\/wp-content\/uploads\/2025\/10\/Meta-Lockup-v2b.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@integralads","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/","url":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/","name":"IAS presenta al mercato la prima misurazione indipendente basata su AI per rilevare Brand Safety &amp; Suitability su Threads di Meta - Integral Ad Science","isPartOf":{"@id":"https:\/\/integralads.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/#primaryimage"},"image":{"@id":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/#primaryimage"},"thumbnailUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2025\/10\/Meta-Lockup-v2b.png","datePublished":"2025-10-16T18:34:00+00:00","dateModified":"2025-10-30T16:43:32+00:00","breadcrumb":{"@id":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/#primaryimage","url":"https:\/\/integralads.com\/wp-content\/uploads\/2025\/10\/Meta-Lockup-v2b.png","contentUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2025\/10\/Meta-Lockup-v2b.png","width":1200,"height":1200,"caption":"Meta - Lockup v2b"},{"@type":"BreadcrumbList","@id":"https:\/\/integralads.com\/it\/news\/ias-presenta-al-mercato-la-prima-misurazione-indipendente-basata-su-aiper-rilevare-brand-safety-e-suitability-su-threads-di-meta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/integralads.com\/it\/"},{"@type":"ListItem","position":2,"name":"IAS presenta al mercato la prima misurazione indipendente basata su AI per rilevare Brand Safety &amp; Suitability su Threads di Meta"}]},{"@type":"WebSite","@id":"https:\/\/integralads.com\/#website","url":"https:\/\/integralads.com\/","name":"Integral Ad Science","description":"The Hidden Cost of MFA Webinar","publisher":{"@id":"https:\/\/integralads.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/integralads.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/integralads.com\/#organization","name":"Integral Ad Science","url":"https:\/\/integralads.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/integralads.com\/#\/schema\/logo\/image\/","url":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/10\/IAS_Square-Logo-600x600-1.png","contentUrl":"https:\/\/integralads.com\/wp-content\/uploads\/2023\/10\/IAS_Square-Logo-600x600-1.png","width":600,"height":600,"caption":"Integral Ad Science"},"image":{"@id":"https:\/\/integralads.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/integralads"]}]}},"_links":{"self":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio\/344182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio\/344182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/media\/344023"}],"wp:attachment":[{"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/media?parent=344182"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/integralads.com\/it\/wp-json\/wp\/v2\/portfolio-types?post=344182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}